{"id":18,"count":22,"description":"Nous proposons une gamme compl\u00e8te de si\u00e8ges auto innovants, s\u00e9curis\u00e9s et confortables pour les enfants de tous \u00e2ges \u2013 du si\u00e8ge auto pour b\u00e9b\u00e9, en passant par un si\u00e8ge auto dos \u00e0 la route et enfin un rehausseur.","link":"https:\/\/axkid.com\/fr\/sieges-auto\/","name":"Tous les si\u00e8ges auto","slug":"sieges-auto","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":22,"acf":[],"_links":{"self":[{"href":"https:\/\/axkid.com\/fr\/wp-json\/wp\/v2\/product_cat\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axkid.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/axkid.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/axkid.com\/fr\/wp-json\/wp\/v2\/product?product_cat=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}